{"id":2205,"count":2,"description":"","link":"https:\/\/level27.pl\/en\/tag\/rooftop-party\/","name":"rooftop party","slug":"rooftop-party","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>rooftop party Archives - level 27 Rooftop in Warsaw<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rooftop party Archives - level 27 Rooftop in Warsaw\" \/>\n<meta property=\"og:url\" content=\"https:\/\/level27.pl\/en\/tag\/rooftop-party\/\" \/>\n<meta property=\"og:site_name\" content=\"level 27 Rooftop in Warsaw\" \/>\n<meta property=\"og:image\" content=\"https:\/\/level27.pl\/wp-content\/uploads\/2025\/10\/new-WWW-thumbnail-level-27.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/tag\\\/rooftop-party\\\/\",\"url\":\"https:\\\/\\\/level27.pl\\\/en\\\/tag\\\/rooftop-party\\\/\",\"name\":\"rooftop party Archives - level 27 Rooftop in Warsaw\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/tag\\\/rooftop-party\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/tag\\\/rooftop-party\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/level27.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"rooftop party\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/level27.pl\\\/en\\\/\",\"name\":\"level 27 Rooftop w Warszawie\",\"description\":\"Parties under the stars\",\"publisher\":{\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/level27.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/#organization\",\"name\":\"Level27\",\"url\":\"https:\\\/\\\/level27.pl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/level27.pl\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/level27.pl\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"width\":224,\"height\":51,\"caption\":\"Level27\"},\"image\":{\"@id\":\"https:\\\/\\\/level27.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"rooftop party Archives - level 27 Rooftop in Warsaw","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"rooftop party Archives - level 27 Rooftop in Warsaw","og_url":"https:\/\/level27.pl\/en\/tag\/rooftop-party\/","og_site_name":"level 27 Rooftop in Warsaw","og_image":[{"width":2000,"height":1125,"url":"https:\/\/level27.pl\/wp-content\/uploads\/2025\/10\/new-WWW-thumbnail-level-27.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/level27.pl\/en\/tag\/rooftop-party\/","url":"https:\/\/level27.pl\/en\/tag\/rooftop-party\/","name":"rooftop party Archives - level 27 Rooftop in Warsaw","isPartOf":{"@id":"https:\/\/level27.pl\/en\/#website"},"breadcrumb":{"@id":"https:\/\/level27.pl\/en\/tag\/rooftop-party\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/level27.pl\/en\/tag\/rooftop-party\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/level27.pl\/en\/"},{"@type":"ListItem","position":2,"name":"rooftop party"}]},{"@type":"WebSite","@id":"https:\/\/level27.pl\/en\/#website","url":"https:\/\/level27.pl\/en\/","name":"level 27 Rooftop w Warszawie","description":"Parties under the stars","publisher":{"@id":"https:\/\/level27.pl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/level27.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/level27.pl\/en\/#organization","name":"Level27","url":"https:\/\/level27.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/level27.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/level27.pl\/wp-content\/uploads\/2019\/04\/logo.png","contentUrl":"https:\/\/level27.pl\/wp-content\/uploads\/2019\/04\/logo.png","width":224,"height":51,"caption":"Level27"},"image":{"@id":"https:\/\/level27.pl\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/level27.pl\/en\/wp-json\/wp\/v2\/tags\/2205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/level27.pl\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/level27.pl\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/level27.pl\/en\/wp-json\/wp\/v2\/posts?tags=2205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}